{"id":15432,"date":"2024-05-06T01:59:32","date_gmt":"2024-05-06T01:59:32","guid":{"rendered":"https:\/\/www.lsvisionhd.com\/product\/2megapixeloutdoorwirelesswifi3g4glteipsolarpanelcameralowpowersmarthomewifibatterycctvptzcamera\/"},"modified":"2024-06-18T09:19:20","modified_gmt":"2024-06-18T09:19:20","slug":"lsvision-2-megapixel-outdoor-wireless-wifi-3g-4g-lte-ip-solar-panel-camera-low-power-smart-home-wifi-battery-cctv-ptz-camera-main-products","status":"publish","type":"product","link":"https:\/\/www.lsvisionhd.com\/it\/product\/lsvision-2-megapixel-outdoor-wireless-wifi-3g-4g-lte-ip-solar-panel-camera-low-power-smart-home-wifi-battery-cctv-ptz-camera-main-products\/","title":{"rendered":"LSVISION &#8211; 2 Megapixel Outdoor Wireless Wifi 3G 4G LTE IP Solar Panel Camera Low Power Smart Home Wifi Battery CCTV PTZ Camera Main Products"},"content":{"rendered":"<div>\n<p>After months of furious yet meaningful development work, Shenzhen LSVISION Technology Co., Ltd. has made it a great success to work out 2 Megapixel Outdoor Wireless Wifi 3G 4G LTE IP Solar Panel Camera Low Power Smart Home Wifi Battery CCTV PTZ Camera. The product is supplied with multiple features and a broad range of applications. The continued success of our product has been built upon consistent and competitive pricing, quality workmanship, quick response time and outstanding customer service. Contact us directly by email or phone call to get more information about our products or services.<\/p>\n<div class=\"rich-text-table\">\n<table>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Luogo di origine:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Guangdong, Cina<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Nome del marchio:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">VISIONE LS<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Numero di modello:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">LS-WS10<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Garanzia:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">1 anno<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Caratteristiche speciali:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Human Motion Tracking, PAN-TILT, Two-way Audio, Low  Power<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Sensore:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">CMOS<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Stile:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">solar camera, PTZ camera<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Funzione:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Two-way Audio, PAN-TILT, NIGHT VISION, Waterproof \/ Weatherproof, Wide Angle<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Formato di compressione video:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">H.265<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Opzioni di archiviazione dei dati:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Cloud, Full HD, Memory Card<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Applicazione:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">All'aperto<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Supporto personalizzato:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Online technical support, Customized logo, OEM, ODM<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Nome del prodotto:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Solar camera<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Wifi:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Yes, 4g is optional<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Risoluzione:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">1920*1080P<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Caratteristica:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Two way voice intercom<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Stoccaggio:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Cloud, memory card<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">APP:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Ubox(Tuya is optional)<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Obiettivo:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">Obiettivo fisso da 3,6 mm<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Distanza IR:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">15m<\/td>\n<\/tr>\n<tr>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Impermeabile:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">IP 66<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px;background:#f8fafc\">Certificazione:<\/td>\n<td style=\"width:25%;padding:5px 20px;font-size:14px\">CE,FCC,Rohs<\/td>\n<\/tr>\n<\/table>\n<\/div>\n<p><\/p>\n<div data-magic-global=\"%7B%22bizId%22%3A17381105403%2C%22pageId%22%3A5019178040%2C%22siteId%22%3A5005162190%7D\" id=\"detail_decorate_root\">\n<div id=\"24710447010\" class=\"J_module\"><\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-5rjpgt\" data-section=\"AliMagic-5rjpgt\" data-section-title=\"Product Description\" class=\"magic-0\">Descrizione del prodotto<\/div>\n<\/div>\n<div class=\"J_module\">\n<div data-magic='{\"mds\":{\"assetsVersion\":\"0.0.14\",\"assetsPackageName\":\"icbumod\",\"moduleNameAlias\":\"icbu-pc-detailSellerRecommend\",\"moduleData\":{\"config\":{\"columnCount\":4,\"titleKey\":6,\"products\":[1600137476207,1600300829425,60697078560,62115732661,50045935035,1600159803277,60789929057,62174618807]}}},\"version\":1}' class=\"icbu-pc-detailSellerRecommend magic-1\"><\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"detail-decorate-json-renderer-container\">\n<div class=\"magic-2\">\n<h3 class=\"magic-3\"><\/h3>\n<h3 class=\"magic-4\"><font color=\"#0000ff\"><span>2 Megapixel Outdoor Indoor Wireless Wifi 3G 4G LTE IP Solar Panel Camera Low Power Smart Home Wifi Battery CCTV PTZ Camera <\/span><\/font><\/h3>\n<div class=\"magic-5\">\n<div class=\"magic-6\">\n<div class=\"magic-7\">\n<p class=\"magic-8\"><font size=\"3\" color=\"#1f1fff\"><span>1. 1080p wifi solar powered battery camera &amp;PTZ camera<br \/>\n2. Pan&amp;Tilt:Pan 355 degree&amp;Tilt 100 degree<br \/>\n3. 3.5 watt solar panel,built-in 15000mAh 3 pcs 21700 batteries<br \/>\n4. Citofono bidirezionale<br \/>\n5. Memoria cloud e scheda TF massima di 128G (senza scheda TF).<br \/>\n6. WIFI 2.4GHz, IEEE 802.11 b\/g\/n, visualizzazione\/riproduzione da remoto tramite APP (UBox)<br \/>\n7. Registrazione video automatica e messaggio push quando il movimento del corpo umano si sveglia<br \/>\n8. Arbitrary arming time can be set<br \/>\n9. 3.6mm lens,built-in infrared light + white light, night vision full color or infrared mode optional IR distance 15 meters<br \/>\n10. Waterproof grade IP66<br \/>\nOptional: Tuya APP  pay 3 dollars more<br \/>\n                  32G TF card pay 5 dollars<\/span><\/font><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"ife-detail-decorate-table\">\n<table class=\"all magic-9\">\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Prodotto:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">4G solar panel cctv power system<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Sensore di immagine:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Sensore CMOS da 1\/3\u2033 a scansione progressiva<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Sistema singolo:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">PAL \/ NTSC regolabile<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Modalit\u00e0 di scansione:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Scansione progressiva<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Illuminazione:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Colore 0,02 lux, bianco e nero 0,02 lux, IR on0 .lux<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Obiettivo:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Standard with 3.0 megapixel,  3.6mm lens<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Interruttore giorno e notte:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">I doppi filtri ottici IR-CUT si attivano automaticamente di giorno e di notte.<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Otturatore elettronico:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Manuale \/ automatico (regolabile, 1 \/ 25 ~ 1 \/ 4000 secondi)<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Bilanciamento del bianco:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Auto \/ manuale<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">DNR<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">3D-DNR<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Fonte IR:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">4pcs array IR<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Distanza IR:<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">30meters<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">FDD-LTE<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">B1\/B2\/B3\/B4\/B7\/B8\/B12\/B13B\/B18\/B19\/B20\/B26<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">TDD-LTE<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">B38\/B39\/B40\/B41<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">WCDMA\/TD-SCDMA<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">B1\/B2\/B4\/B5\/B8\/B34\/B39<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">GSM\/GPRS\/EDGE<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">900\/1800MHz<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Compressione dell'immagine<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">H.264<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Velocit\u00e0 di trasmissione video<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">128 Kbps - 8 Mbps; CBR \/ VBR regolabile<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Dimensione massima dell'immagine<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">1920*1080<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Dimensioni del telaio<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\"> 1920*1080 @ 30 fps; 1280 x 720 @ 30 fps; 704 x 576 @ 25 fps; 640 x 360 @ 25 fps; 352 x 88 @ 25 fps <\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Regolazione dell'immagine<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Tramite IE \u00e8 possibile regolare saturazione, luminosit\u00e0, contrasto, nitidezza.<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Specchio d'immagine<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Mirroring orizzontale, mirroring verticale<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">scena<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Auto, interno, esterno<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Ingrandimento digitale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Pu\u00f2 essere raggiunto attraverso il software di gestione NVR, P2P HDmonitoraggio<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Immagazzinamento<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Supporto scheda di memoria TF 64G<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Protocollo di interfaccia<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">onvif<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Protocollo di supporto<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">TCP \/ IP, ICMP, HTTP, HTTPS, FTP, DHCP, DNS, DDNS, RTP, RTSP, RTCP, PPPoE, NTP, UPnP, SMTP, SNMP, IGMP, 802.1x, QoS, IPv6, Bonjour (SIP, SRTP opzionale)<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Allarme intelligente<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Rilevamento del movimento, allarme maschera, cavo di rete interrotto, conflitto di indirizzi IP, scheda di memoria piena, dispositivo di memoria errato.<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">wifi<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">Funzione WIFI di supporto <\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Interfaccia di comunicazione<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">1pc RJ45 10M \/ 100M Porta Adaptive Ethernet<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Ingresso di alimentazione<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">DC 12V\u00b110% <\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Potenza assorbita<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">4 W (IR spento) \/ 9,8 W (IR acceso)<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">Ambiente di lavoro<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">35\u2103; - 60\u2103, umidit\u00e0 inferiore a 95% (senza condensa)<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-10\">dimensione<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-11\">183 mm*91 mm*66 mm<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-ao9rtm\" data-section=\"AliMagic-ao9rtm\" data-section-title=\"wifi and sim card\" class=\"magic-0\">wifi and sim card<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-13\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H8d35fc0f500a45138b36b80d746d9340M.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H8d35fc0f500a45138b36b80d746d9340M.jpg\" class=\"magic-14 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H8d35fc0f500a45138b36b80d746d9340M.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H8d35fc0f500a45138b36b80d746d9340M.jpg\" class=\"magic-14 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-15\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H9e0fcdab4fb843148d229dfdde906f25s.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H9e0fcdab4fb843148d229dfdde906f25s.jpg\" class=\"magic-16 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H9e0fcdab4fb843148d229dfdde906f25s.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H9e0fcdab4fb843148d229dfdde906f25s.jpg\" class=\"magic-16 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-17\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hcca866307d2b403ab260dd7965dcb3den.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hcca866307d2b403ab260dd7965dcb3den.jpg\" class=\"magic-18 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hcca866307d2b403ab260dd7965dcb3den.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hcca866307d2b403ab260dd7965dcb3den.jpg\" class=\"magic-18 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-19\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hec93457cab634b029ead5dfb6bd72c58m.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hec93457cab634b029ead5dfb6bd72c58m.jpg\" class=\"magic-20 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hec93457cab634b029ead5dfb6bd72c58m.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hec93457cab634b029ead5dfb6bd72c58m.jpg\" class=\"magic-20 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-21\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hba18eda55ec947f8887f349f10740760R.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hba18eda55ec947f8887f349f10740760R.jpg\" class=\"magic-22 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hba18eda55ec947f8887f349f10740760R.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hba18eda55ec947f8887f349f10740760R.jpg\" class=\"magic-22 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-23\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H572b1ba0f8cd4418a151bb179a14baabk.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H572b1ba0f8cd4418a151bb179a14baabk.jpg\" class=\"magic-24 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H572b1ba0f8cd4418a151bb179a14baabk.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H572b1ba0f8cd4418a151bb179a14baabk.jpg\" class=\"magic-24 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-25\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H83c9329c29e94e08acacc630a2a93cb0Z.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H83c9329c29e94e08acacc630a2a93cb0Z.jpg\" class=\"magic-26 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H83c9329c29e94e08acacc630a2a93cb0Z.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H83c9329c29e94e08acacc630a2a93cb0Z.jpg\" class=\"magic-26 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-27\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H999a4d454f6a438bb4b93fc5b4546d51s.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H999a4d454f6a438bb4b93fc5b4546d51s.jpg\" class=\"magic-28 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H999a4d454f6a438bb4b93fc5b4546d51s.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H999a4d454f6a438bb4b93fc5b4546d51s.jpg\" class=\"magic-28 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-29\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H2bdf02bfd63449ed80627d0facadc071J.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H2bdf02bfd63449ed80627d0facadc071J.jpg\" class=\"magic-30 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H2bdf02bfd63449ed80627d0facadc071J.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H2bdf02bfd63449ed80627d0facadc071J.jpg\" class=\"magic-30 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-31\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Ha75f9f99ce364be1a922a3a9fc969938W.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Ha75f9f99ce364be1a922a3a9fc969938W.jpg\" class=\"magic-32 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Ha75f9f99ce364be1a922a3a9fc969938W.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Ha75f9f99ce364be1a922a3a9fc969938W.jpg\" class=\"magic-32 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-33\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H972d2e26347247c9894719d7e0dd31b9x.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H972d2e26347247c9894719d7e0dd31b9x.jpg\" class=\"magic-34 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H972d2e26347247c9894719d7e0dd31b9x.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H972d2e26347247c9894719d7e0dd31b9x.jpg\" class=\"magic-34 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-35\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H52b568cfb0594954ad488c715cec00496.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H52b568cfb0594954ad488c715cec00496.jpg\" class=\"magic-36 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H52b568cfb0594954ad488c715cec00496.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H52b568cfb0594954ad488c715cec00496.jpg\" class=\"magic-36 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-bkwstt\" data-section=\"AliMagic-bkwstt\" data-section-title=\"Install area\" class=\"magic-0\">Area di installazione<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-37\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/HTB1CNdWXwCYW1JjSZFCq6AxLVXa7.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/HTB1CNdWXwCYW1JjSZFCq6AxLVXa7.jpg\" class=\"magic-38 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/HTB1CNdWXwCYW1JjSZFCq6AxLVXa7.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/HTB1CNdWXwCYW1JjSZFCq6AxLVXa7.jpg\" class=\"magic-38 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-m7n5s2\" data-section=\"AliMagic-m7n5s2\" data-section-title=\"LS VISION\" class=\"magic-0\">VISIONE LS<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-39\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H0e41ec6bc21f467995d4316826a8cbdbj.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H0e41ec6bc21f467995d4316826a8cbdbj.jpg\" class=\"magic-40 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H0e41ec6bc21f467995d4316826a8cbdbj.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H0e41ec6bc21f467995d4316826a8cbdbj.jpg\" class=\"magic-40 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"detail-decorate-json-renderer-container\">\n<div class=\"magic-2\">\n<h3 class=\"magic-41\"><span><font class=\"magic-42\">Shenzhen ls vision Technology Co., Ltd.<\/font><\/span><\/h3>\n<div class=\"magic-5\">\n<div class=\"magic-6\">\n<div class=\"magic-7\">\n<div>LS VISION si concentra sulle soluzioni di sorveglianza della sicurezza dal 2010.<br \/>\nAbbiamo ottenuto il titolo di \"China High-Tech Enterprises\".<br \/>\nIn combinazione con le apparecchiature hardware e software di monitoraggio,<br \/>\nper l'utente globale per fornire sicurezza, soluzioni e servizi per la casa intelligente.<br \/>\nL'azienda \u00e8 impegnata nel settore della sicurezza intelligente e della casa intelligente.<br \/>\nLS VISION Valore fondamentale: \"Qualit\u00e0, innovazione, dedizione\".<br \/>\nMissione LS VISION:  \"Creare un mondo pi\u00f9 sicuro e pi\u00f9 verde\".\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-43\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H1c47ffdbfde94172aefeb454ac556fe7k.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H1c47ffdbfde94172aefeb454ac556fe7k.jpg\" class=\"magic-44 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H1c47ffdbfde94172aefeb454ac556fe7k.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H1c47ffdbfde94172aefeb454ac556fe7k.jpg\" class=\"magic-44 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-7cobj5\" data-section=\"AliMagic-7cobj5\" data-section-title=\"Certifications\" class=\"magic-45\">Certificazioni<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-46\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H7fe80c62d8e84d95a113118b616223ban.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H7fe80c62d8e84d95a113118b616223ban.jpg\" class=\"magic-47 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H7fe80c62d8e84d95a113118b616223ban.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/H7fe80c62d8e84d95a113118b616223ban.jpg\" class=\"magic-47 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-aojej7\" data-section=\"AliMagic-aojej7\" data-section-title=\"Exhibition\" class=\"magic-45\">Mostra<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-48\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Ha2242e6c06264f3f90524e217c01f3910.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Ha2242e6c06264f3f90524e217c01f3910.jpg\" class=\"magic-49 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Ha2242e6c06264f3f90524e217c01f3910.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Ha2242e6c06264f3f90524e217c01f3910.jpg\" class=\"magic-49 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-50\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Hbcfb8c9f17a34a27bfa1ac1fad420e8do.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Hbcfb8c9f17a34a27bfa1ac1fad420e8do.jpg\" class=\"magic-51 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Hbcfb8c9f17a34a27bfa1ac1fad420e8do.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/04\/Hbcfb8c9f17a34a27bfa1ac1fad420e8do.jpg\" class=\"magic-51 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-52\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hb366cd6cb5be4768a6126bf09b4343b1E.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hb366cd6cb5be4768a6126bf09b4343b1E.jpg\" class=\"magic-53 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hb366cd6cb5be4768a6126bf09b4343b1E.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/Hb366cd6cb5be4768a6126bf09b4343b1E.jpg\" class=\"magic-53 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-xqko2o\" data-section=\"AliMagic-xqko2o\" data-section-title=\"Logistics\" class=\"magic-45\">Logistics<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"icbu-pc-images magic-12\">\n<div>\n<div class=\"flex-layout-v\">\n<div class=\"flex-layout-h magic-12\">\n<div class=\"magic-54\">\n<img decoding=\"async\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H554f360f9478497baf3af1288af66f5d7.jpg\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H554f360f9478497baf3af1288af66f5d7.jpg\" class=\"magic-55 img-self\"><img decoding=\"async\" data-src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H554f360f9478497baf3af1288af66f5d7.jpg\" src=\"https:\/\/www.lsvisionhd.com\/wp-content\/uploads\/2024\/05\/H554f360f9478497baf3af1288af66f5d7.jpg\" class=\"magic-55 img-self\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div id=\"ali-anchor-AliMagic-703tix\" data-section=\"AliMagic-703tix\" data-section-title=\"FAQ\" class=\"magic-45\">FAQ<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"detail-decorate-json-renderer-container\">\n<div class=\"magic-2\">\n<div class=\"magic-5\">\n<div class=\"magic-6\">\n<div class=\"magic-7\">\n<span>1. chi siamo?<br \/><span>LS VISION Technology Co., Ltd. \u00e8 un fornitore di soluzioni di videosorveglianza full HD. Abbiamo ottenuto il titolo di \"China High Tech Enterprises\", \"Shenzhen High Tech Enterprises\" e \"Member Unit of Shenzhen Smart Security Chamber of Commerce\".<\/span><\/span><\/p>\n<div><span><span><span>Linea di prodotti principali:<span>Telecamera IP; Kit NVR; Telecamera domestica senza fili; Telecamera ad energia solare; Telecamera PTZ; Telecamera per immagini termiche, telecamera scanner di temperatura.<\/span><\/span><br \/><\/span><\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"ife-detail-decorate-table\">\n<table class=\"has-title hight-light-first-column all magic-9\">\n<tbody>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Mercati principali<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">Entrate totali (%)<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Europa orientale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">20.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Sud America<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">10.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Europa occidentale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">10.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">America Centrale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">10.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Europa del Nord<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">10.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Europa meridionale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">10.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Nord America<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">5.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Sud-est asiatico<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">5.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Africa<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">5.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Oceania<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">5.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Asia orientale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">3.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Mercato nazionale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">3.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Medio Oriente<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">2.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-56\">Asia meridionale<\/div>\n<\/td>\n<td colspan=\"1\" rowspan=\"1\">\n<div class=\"magic-57\">\n<div class=\"magic-58\">2.00%<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div class=\"J_module\">\n<div class=\"detail-decorate-json-renderer-container\">\n<div class=\"magic-2\">\n<div class=\"magic-5\">\n<div class=\"magic-6\">\n<div class=\"magic-7\">\n<div><span>2. Come possiamo garantire la qualit\u00e0?<br \/>Sempre un campione di pre-produzione prima della produzione di massa;<br \/>Ispezione finale prima della spedizione;<\/p>\n<p>3.cosa si pu\u00f2 acquistare da noi?<br \/>Telecamera IP, kit NVR, videocamera domestica wireless, videocamera solare \/ PTZ, videocamera di misurazione della temperatura con riconoscimento facciale AI<\/p>\n<p>4. perch\u00e9 dovreste acquistare da noi e non da altri fornitori?<br \/>LSVISION, impresa cinese ad alta tecnologia. 15 anni di esperienza nella ricerca e sviluppo in materia di sicurezza, fornitore per la videosorveglianza e la casa intelligente.<br \/>Tutti i prodotti hanno superato i test CE, RoHS, FCC e ISO9001. pi\u00f9 di 10 agenzie esclusive globali.<\/p>\n<p>5. quali servizi possiamo fornire?<br \/>Termini di consegna accettati: FOB, CIF, EXW\uff1b<br \/>Valuta di pagamento accettata: USD, EUR, CNY;<br \/>Tipo di pagamento accettato: T\/T, carta di credito, PayPal, Western Union, contanti;<br \/>Lingua parlata: inglese, cinese<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>2 Megapixel Outdoor Wireless Wifi 3G 4G LTE IP Solar Panel Camera Low Power Smart Home Wifi Battery CCTV PTZ Camera has been widely acclaimed for its competitive characteristics because we have been subject to meeting the industry standard.The fields of application include Main Products.  <\/p>","protected":false},"featured_media":15431,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[197],"product_tag":[],"class_list":["post-15432","product","type-product","status-publish","has-post-thumbnail","product_cat-solar-cameras","desktop-align-left","tablet-align-left","mobile-align-left","ast-product-gallery-layout-horizontal-slider","ast-product-tabs-layout-horizontal","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/product\/15432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/comments?post=15432"}],"version-history":[{"count":0,"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/product\/15432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/media\/15431"}],"wp:attachment":[{"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/media?parent=15432"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/product_brand?post=15432"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/product_cat?post=15432"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.lsvisionhd.com\/it\/wp-json\/wp\/v2\/product_tag?post=15432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}